{"id":137,"date":"2026-06-18T21:39:33","date_gmt":"2026-06-18T21:39:33","guid":{"rendered":"https:\/\/simplemusicmethod.com\/?page_id=137"},"modified":"2026-07-09T18:03:33","modified_gmt":"2026-07-09T18:03:33","slug":"contact","status":"publish","type":"page","link":"https:\/\/simplemusicmethod.com\/en\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"137\" class=\"elementor elementor-137\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f524541 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f524541\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36e0db91\" data-id=\"36e0db91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-312174b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"312174b7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5466c1c1\" data-id=\"5466c1c1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-618c3675 elementor-widget elementor-widget-heading\" data-id=\"618c3675\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cont\u00e1ctanos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4867901b elementor-section-content-middle elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4867901b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-75596784\" data-id=\"75596784\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-430004dd elementor-widget elementor-widget-heading\" data-id=\"430004dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hablemos de M\u00fasica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50381475 elementor-widget elementor-widget-text-editor\" data-id=\"50381475\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ya sea que est\u00e9s buscando clases para ti, para un familiar o simplemente quieras conocer m\u00e1s sobre SimpleMusic, estaremos encantados de ayudarte. Completa el formulario y nos pondremos en contacto contigo lo antes posible.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4aa17f1b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4aa17f1b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-336e0d46\" data-id=\"336e0d46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c8ba663 elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"6c8ba663\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">C\u00f3mo Podemos Ayudarte?<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4176f08d elementor-widget elementor-widget-metform\" data-id=\"4176f08d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"metform.default\">\n\t\t\t\t\t<div id=\"mf-response-props-id-519\" data-previous-steps-style=\"\" data-editswitchopen=\"\" data-response_type=\"alert\" data-erroricon=\"fas fa-exclamation-triangle\" data-successicon=\"fas fa-check\" data-messageposition=\"top\" class=\"   mf-scroll-top-no\">\n\t\t<div class=\"formpicker_warper formpicker_warper_editable\" data-metform-formpicker-key=\"519\" >\n\t\t\t\t\n\t\t\t<div class=\"mf-widget-container\">\n\t\t\t\t\r\n\t\t<div\r\n\t\t\tid=\"metform-wrap-4176f08d-519\"\r\n\t\t\tclass=\"mf-form-wrapper\"\r\n\t\t\tdata-form-id=\"519\"\r\n\t\t\tdata-action=\"https:\/\/simplemusicmethod.com\/en\/wp-json\/metform\/v1\/entries\/insert\/519\"\r\n\t\t\tdata-wp-nonce=\"4157869c8d\"\r\n\t\t\tdata-form-nonce=\"b0edf083f1\"\r\n\t\t\tdata-quiz-summery = \"false\"\r\n\t\t\tdata-save-progress = \"false\"\r\n\t\t\tdata-form-type=\"general-form\"\r\n\t\t\tdata-stop-vertical-effect=\"\"\r\n\t\t\tdata-payment-submit-before=\"\"\r\n\t\t\t><\/div>\r\n\r\n\r\n\t\t<!----------------------------- \r\n\t\t\t* controls_data : find the the props passed indie of data attribute\r\n\t\t\t* props.SubmitResponseMarkup : contains the markup of error or success message\r\n\t\t\t* https:\/\/developer.mozilla.org\/en-US\/docs\/Web\/JavaScript\/Reference\/Template_literals\r\n\t\t--------------------------- -->\r\n\r\n\t\t\t\t<script type=\"text\/mf\" class=\"mf-template\">\r\n\t\t\tfunction controls_data (value){\r\n\t\t\t\tlet currentWrapper = \"mf-response-props-id-519\";\r\n\t\t\t\tlet currentEl = document.getElementById(currentWrapper);\r\n\t\t\t\t\r\n\t\t\t\treturn currentEl ? currentEl.dataset[value] : false\r\n\t\t\t}\r\n\r\n\r\n\t\t\tlet is_edit_mode = '' ? true : false;\r\n\t\t\tlet message_position = controls_data('messageposition') || 'top';\r\n\r\n\t\t\t\r\n\t\t\tlet message_successIcon = controls_data('successicon') || '';\r\n\t\t\tlet message_errorIcon = controls_data('erroricon') || '';\r\n\t\t\tlet message_editSwitch = controls_data('editswitchopen') === 'yes' ? true : false;\r\n\t\t\tlet message_proClass = controls_data('editswitchopen') === 'yes' ? 'mf_pro_activated' : '';\r\n\t\t\t\r\n\t\t\tlet is_dummy_markup = is_edit_mode && message_editSwitch ? true : false;\r\n\r\n\t\t\t\r\n\t\t\treturn html`\r\n\t\t\t\t<form\r\n\t\t\t\t\tclassName=\"metform-form-content\"\r\n\t\t\t\t\tref=${parent.formContainerRef}\r\n\t\t\t\t\tonSubmit=${ validation.handleSubmit( parent.handleFormSubmit ) }\r\n\t\t\t\t\r\n\t\t\t\t\t>\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'top' ?  props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' :  message_position === 'top' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\r\n\t\t\t\t\t<!--------------------------------------------------------\r\n\t\t\t\t\t*** IMPORTANT \/ DANGEROUS ***\r\n\t\t\t\t\t${html``} must be used as in immediate child of \"metform-form-main-wrapper\"\r\n\t\t\t\t\tclass otherwise multistep form will not run at all\r\n\t\t\t\t\t---------------------------------------------------------->\r\n\r\n\t\t\t\t\t<div className=\"metform-form-main-wrapper\" key=${'hide-form-after-submit'} ref=${parent.formRef}>\r\n\t\t\t\t\t${html`\r\n\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" key=\"2\" data-elementor-id=\"519\" className=\"elementor elementor-519\">\n\t\t\t\t<div className=\"elementor-element elementor-element-46a3f1bf e-con-full e-flex e-con e-parent\" data-id=\"46a3f1bf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div className=\"elementor-element elementor-element-65b14f34 e-con-full e-grid e-con e-child\" data-id=\"65b14f34\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div className=\"elementor-element elementor-element-229b8a8 elementor-widget elementor-widget-mf-text\" data-id=\"229b8a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-first-name&quot;}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-229b8a8\">\r\n\t\t\t\t\t${ parent.decodeEntities(`First Name`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\r\n\t\t\t\tid=\"mf-input-text-229b8a8\"\r\n\t\t\t\tname=\"mf-first-name\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`First name here`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-first-name'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-first-name\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-1a922000 elementor-widget elementor-widget-mf-text\" data-id=\"1a922000\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-last-name&quot;}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-1a922000\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Last Name`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\r\n\t\t\t\tid=\"mf-input-text-1a922000\"\r\n\t\t\t\tname=\"mf-last-name\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Last name here`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-last-name'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-last-name\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-752b6f44 elementor-widget elementor-widget-mf-email\" data-id=\"752b6f44\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-email&quot;}\" data-widget_type=\"mf-email.default\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-email-752b6f44\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Email Address`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input \r\n\t\t\t\ttype=\"email\" \r\n\t\t\t\t \r\n\t\t\t\tdefaultValue=\"\" \r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\" \r\n\t\t\t\tid=\"mf-input-email-752b6f44\" \r\n\t\t\t\tname=\"mf-email\" \r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Add email`) } \" \r\n\t\t\t\t \r\n\t\t\t\tonBlur=${parent.handleChange} onFocus=${parent.handleChange} aria-invalid=${validation.errors['mf-email'] ? 'true' : 'false' } \r\n\t\t\t\tref=${el=> parent.activateValidation({\"message\":\"This field is required.\",\"emailMessage\":\"Please enter a valid Email address\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t<${validation.ErrorMessage} \r\n\t\t\t\terrors=${validation.errors} \r\n\t\t\t\tname=\"mf-email\" \r\n\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-452c321f elementor-widget elementor-widget-mf-text\" data-id=\"452c321f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-subject&quot;}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-452c321f\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Subject`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\r\n\t\t\t\tid=\"mf-input-text-452c321f\"\r\n\t\t\t\tname=\"mf-subject\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`How can we help you?`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-subject'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-subject\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-13f46608 elementor-widget__width-inherit elementor-widget elementor-widget-mf-textarea\" data-id=\"13f46608\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-comment&quot;}\" data-widget_type=\"mf-textarea.default\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-area-13f46608\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Comments \/ Questions`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<textarea className=\"mf-input mf-textarea mf-conditional-input\" id=\"mf-input-text-area-13f46608\"\r\n\t\t\t\tname=\"mf-comment\" \r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Comments`) } \"\r\n\t\t\t\tcols=\"30\" rows=\"10\"\r\n\t\t\t\t\t\t\t\t\tonInput=${ parent.handleChange }\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-comment'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${ el => parent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\t><\/textarea>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-comment\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-50e956bc elementor-widget__width-inherit elementor-widget elementor-widget-mf-recaptcha\" data-id=\"50e956bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mf-recaptcha.default\">\n\t\t\t\t\t\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\n\t\t\t\t\t<div\n\t\t\t\t\t\tclassName=\"g-recaptcha \"\n\t\t\t\t\t\tid=\"g-recaptcha\"\n\t\t\t\t\t\tdata-sitekey=\"dummy\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tdata-callback=\"handleReCAPTCHA_${this.state.recaptcha_uid}\"\n\t\t\t\t\t\t\tdata-expired-callback=\"handleReCAPTCHA_${this.state.recaptcha_uid}\"\n\t\t\t\t\t\t\tdata-error-callback=\"handleReCAPTCHA_${this.state.recaptcha_uid}\"\n\t\t\t\t\t\t\taria-invalid=${validation.errors['g-recaptcha-response'] ? 'true' : 'false'}\n\t\t\t\t\t\t\t\t\t\t\t\t><\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<input type=\"hidden\"\n\t\t\t\t\t\t\tname=\"g-recaptcha-response\"\n\t\t\t\t\t\t\tclassName=\"mf-input mf-mobile-hidden\"\n\t\t\t\t\t\t\tvalue=${parent.getValue('g-recaptcha-response')}\n\t\t\t\t\t\t\tref=${el => parent.activateValidation({\"message\":\"reCAPTCHA is required.\",\"required\":true}, el)}\n\t\t\t\t\t\t\t\/>\n\n\t\t\t\t\t\t<${validation.ErrorMessage} errors=${validation.errors} name=\"g-recaptcha-response\" as=${html`<span className=\"mf-error-message\"><\/span>`} \/>\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-54379b03 elementor-widget__width-auto elementor-widget elementor-widget-mf-button\" data-id=\"54379b03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mf-button.default\">\n\t\t\t\t\t\t\t<div className=\"mf-btn-wraper mf-conditional-input\" data-mf-form-conditional-logic-requirement=\"\">\r\n\t\t\t\t\t\t\t<button type=\"submit\" className=\"metform-btn metform-submit-btn \" id=\"\">\r\n\t\t\t\t\t<span>${ parent.decodeEntities(`Send Message`) } <\/span>\r\n\t\t\t\t<\/button>\r\n\t\t\t        <\/div>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t`}\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'bottom' ? props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' : message_position === 'bottom' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\t\t\t\t\r\n\t\t\t\t<\/form>\r\n\t\t\t`\r\n\t\t<\/script>\r\n\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-615cedc7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"615cedc7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6a3f23e8\" data-id=\"6a3f23e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5639e795 jkit-equal-height-disable elementor-widget elementor-widget-jkit_icon_box\" data-id=\"5639e795\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jkit_icon_box.default\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-icon-box icon-position-left elementor-animation- jeg_module___6a57dd08cbc5d\" ><div class=\"jkit-icon-box-wrapper hover-from-left\"><div class=\"icon-box icon-box-header elementor-animation-\"><div class=\"icon style-color\"><i aria-hidden=\"true\" class=\"jki jki-placeholder-light\"><\/i><\/div><\/div><div class=\"icon-box icon-box-body\">\n                <h4 class=\"title\">\u00c1reas de Servicio<\/h4><p class=\"icon-box-description\">Miramar, Hollywood, Pembroke Pines, Cooper City, Weston y ciudades cercanas.<\/p>\n            <\/div>\n            \n            <\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3e8aa60a\" data-id=\"3e8aa60a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78db6d4b jkit-equal-height-disable elementor-widget elementor-widget-jkit_icon_box\" data-id=\"78db6d4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jkit_icon_box.default\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-icon-box icon-position-left elementor-animation- jeg_module__1_6a57dd08cc378\" ><div class=\"jkit-icon-box-wrapper hover-from-left\"><div class=\"icon-box icon-box-header elementor-animation-\"><div class=\"icon style-color\"><i aria-hidden=\"true\" class=\"jki jki-clock2-light\"><\/i><\/div><\/div><div class=\"icon-box icon-box-body\">\n                <h4 class=\"title\">Respondemos<\/h4><p class=\"icon-box-description\"> en menos de 24 horas.<\/p>\n            <\/div>\n            \n            <\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3eb527e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3eb527e0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5ae1e8f1\" data-id=\"5ae1e8f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4745672 elementor-widget__width-initial jkit-equal-height-disable elementor-widget elementor-widget-jkit_icon_box\" data-id=\"4745672\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jkit_icon_box.default\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-icon-box icon-position-left elementor-animation- jeg_module__2_6a57dd08cc95c\" ><div class=\"jkit-icon-box-wrapper hover-from-left\"><div class=\"icon-box icon-box-header elementor-animation-\"><div class=\"icon style-color\"><i aria-hidden=\"true\" class=\"jki jki-envelope3-light\"><\/i><\/div><\/div><div class=\"icon-box icon-box-body\">\n                <h4 class=\"title\">Email<\/h4><p class=\"icon-box-description\">simplemusicmethod@gmaill.com<\/p>\n            <\/div>\n            \n            <\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cont\u00e1ctanos Hablemos de M\u00fasica Ya sea que est\u00e9s buscando clases para ti, para un familiar o simplemente quieras conocer m\u00e1s sobre SimpleMusic, estaremos encantados de ayudarte. Completa el formulario y nos pondremos en contacto contigo lo antes posible. C\u00f3mo Podemos Ayudarte? \u00c1reas de Servicio Miramar, Hollywood, Pembroke Pines, Cooper City, Weston y ciudades cercanas. Respondemos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-137","page","type-page","status-publish","hentry"],"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/simplemusicmethod.com\/en\/wp-json\/wp\/v2\/pages\/137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simplemusicmethod.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/simplemusicmethod.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/simplemusicmethod.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/simplemusicmethod.com\/en\/wp-json\/wp\/v2\/comments?post=137"}],"version-history":[{"count":121,"href":"https:\/\/simplemusicmethod.com\/en\/wp-json\/wp\/v2\/pages\/137\/revisions"}],"predecessor-version":[{"id":1725,"href":"https:\/\/simplemusicmethod.com\/en\/wp-json\/wp\/v2\/pages\/137\/revisions\/1725"}],"wp:attachment":[{"href":"https:\/\/simplemusicmethod.com\/en\/wp-json\/wp\/v2\/media?parent=137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}